{"id":99625,"date":"2020-06-17T09:19:30","date_gmt":"2020-06-17T12:19:30","guid":{"rendered":"http:\/\/diariodamanhapelotas.com.br\/site\/?p=99625"},"modified":"2020-06-22T08:52:45","modified_gmt":"2020-06-22T11:52:45","slug":"coronavirus-no-brasil-pesquisa-inicia-nova-etapa-de-testes-rapidos","status":"publish","type":"post","link":"https:\/\/diariodamanhapelotas.com.br\/site\/coronavirus-no-brasil-pesquisa-inicia-nova-etapa-de-testes-rapidos\/","title":{"rendered":"CORONAV\u00cdRUS NO BRASIL : Pesquisa inicia nova etapa de testes r\u00e1pidos"},"content":{"rendered":"<p><i>Pesquisadores do IBOPE Intelig\u00eancia v\u00e3o aplicar testes r\u00e1pidos para o coronav\u00edrus em visitas domiciliares a moradores de 133 cidades do Brasil entre os dias 21 e 23 de junho<\/i><\/p>\n<p>A pesquisa EPICOVID19-BR, que estima a propor\u00e7\u00e3o de casos de infec\u00e7\u00e3o por coronav\u00edrus no Brasil, inicia nova etapa a partir deste domingo (21), com a meta de realizar 33.250 testes r\u00e1pidos e entrevistas em\u00a0<a href=\"http:\/\/epidemio-ufpel.org.br\/uploads\/downloads\/bd44642ac4b6327acfeb2d2273473061.pdf\">133 cidades de todos os estados do pa\u00eds<\/a>.<\/p>\n<p>Cerca de 2,6 mil pesquisadores do IBOPE Intelig\u00eancia v\u00e3o \u00e0s ruas, nos dias 21, 22 e 23 de junho, para visitar resid\u00eancias e convidar 250 moradores a realizar testes r\u00e1pidos para o coronav\u00edrus em cada uma das cidades inclu\u00eddas na pesquisa.<\/p>\n<p>\u201c\u00c9 fundamental que a popula\u00e7\u00e3o aceite participar da pesquisa. Em cada cidade, por exemplo, \u00e9 preciso realizar pelo menos duzentos testes, para que possamos apresentar estimativas sobre a real dimens\u00e3o da Covid-19. Al\u00e9m de contribuir com o esfor\u00e7o coletivo de enfrentamento da pandemia, o participante tem a oportunidade de realizar o exame e saber o resultado na hora\u201d, diz a epidemiologista Mari\u00e2ngela Freitas da Silveira, integrante da coordena\u00e7\u00e3o do estudo.<\/p>\n<div id=\"attachment_99626\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-99626\" loading=\"lazy\" class=\"size-medium wp-image-99626\" alt=\"ESTUDO \u00e9 coordenado pela UFPel com financiamento do Minist\u00e9rio da Sa\u00fade\" src=\"http:\/\/diariodamanhapelotas.com.br\/site\/wp-content\/uploads\/2020\/06\/pesquisa-corona-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/diariodamanhapelotas.com.br\/site\/wp-content\/uploads\/2020\/06\/pesquisa-corona-300x199.jpg 300w, https:\/\/diariodamanhapelotas.com.br\/site\/wp-content\/uploads\/2020\/06\/pesquisa-corona-150x99.jpg 150w, https:\/\/diariodamanhapelotas.com.br\/site\/wp-content\/uploads\/2020\/06\/pesquisa-corona.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-99626\" class=\"wp-caption-text\">ESTUDO \u00e9 coordenado pela UFPel com financiamento do Minist\u00e9rio da Sa\u00fade<\/p><\/div>\n<p>O Estudo de Preval\u00eancia da Infec\u00e7\u00e3o por Covid-19 no Brasil (EPICOVID19-BR), coordenado pela Universidade Federal de Pelotas com financiamento do Minist\u00e9rio da Sa\u00fade, \u00e9 o maior levantamento populacional do mundo a estimar a preval\u00eancia de Covid-19. A segunda etapa da pesquisa apresentou evid\u00eancias in\u00e9ditas sobre a velocidade de expans\u00e3o do coronav\u00edrus em 83 cidades do pa\u00eds. A propor\u00e7\u00e3o de pessoas que j\u00e1 contra\u00edram o v\u00edrus no Brasil aumentou em 53% no per\u00edodo de duas semanas entre a primeira etapa, realizada de 19 a 21 de maio, e a segunda, de 4 a 5 de junho. Os dados mais recentes tamb\u00e9m mostram que, para cada diagn\u00f3stico confirmado, existem ao redor de seis casos reais n\u00e3o notificados na popula\u00e7\u00e3o. Para se ter uma ideia, as estimativas somam mais de 1,7 milh\u00e3o de pessoas que t\u00eam ou j\u00e1 tiveram o coronav\u00edrus, contra o total de 296.305 casos notificados em 120 cidades brasileiras na v\u00e9spera do segundo levantamento da pesquisa.<\/p>\n<p><strong>COMO FUNCIONA A PESQUISA<\/strong><\/p>\n<p>O estudo inclui a cidade mais populosa de cada uma das 133 sub-regi\u00f5es definidas pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) para o territ\u00f3rio brasileiro. A sele\u00e7\u00e3o das resid\u00eancias e das pessoas que ser\u00e3o entrevistadas e testadas ocorre por meio de um sorteio aleat\u00f3rio, utilizando os setores censit\u00e1rios do IBGE como base.<\/p>\n<p>Para o exame, os pesquisadores coletam uma gota de sangue da ponta do dedo do participante, que ser\u00e1 analisada pelo aparelho de teste em aproximadamente 15 minutos. Enquanto aguarda o resultado, o participante responde a perguntas sobre sintomas da Covid-19 nas \u00faltimas semanas, busca por assist\u00eancia m\u00e9dica e rotina em rela\u00e7\u00e3o \u00e0s medidas de preven\u00e7\u00e3o e isolamento social. Em caso de resultado positivo, os profissionais comunicam a Vigil\u00e2ncia Epidemiol\u00f3gica local.<\/p>\n<p>OS PESQUISADORES que realizam as visitas est\u00e3o identificados por crach\u00e1 do IBOPE Intelig\u00eancia e utilizam os equipamentos de prote\u00e7\u00e3o individuais (EPIs): m\u00e1scaras, toucas, aventais, sapatilhas (todos descart\u00e1veis), \u00f3culos de prote\u00e7\u00e3o e luvas. Todos os profissionais s\u00e3o testados e apenas aqueles que tiverem resultado negativo realizam as visitas domiciliares. O estudo tem aprova\u00e7\u00e3o da Comiss\u00e3o Nacional de \u00c9tica em Pesquisa e cumpre todos os requisitos de seguran\u00e7a necess\u00e1rios, para proteger os pesquisadores e a popula\u00e7\u00e3o.<\/p>\n<p>Em caso de d\u00favidas, os participantes podem entrar em contato para esclarecimentos sobre as visitas \u00e0s casas pelos telefones 0800-800-5000, (11) 3335-8583, (11) 3335-8606; (11) 3335-8610, ou pelos e-mails\u00a0<a href=\"mailto:pesquisa.covid-19@ufpel.edu.br\">pesquisa.covid-19@ufpel.edu.br<\/a>\u00a0e\u00a0<a href=\"mailto:pesquisa.covid-19@ibopeinteligencia.com\">pesquisa.covid-19@ibopeinteligencia.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisadores do IBOPE Intelig\u00eancia v\u00e3o aplicar testes r\u00e1pidos para o coronav\u00edrus em visitas domiciliares a moradores de 133 cidades do Brasil entre os dias 21 e 23 de junho A<\/p>\n","protected":false},"author":4,"featured_media":99626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/posts\/99625"}],"collection":[{"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/comments?post=99625"}],"version-history":[{"count":1,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/posts\/99625\/revisions"}],"predecessor-version":[{"id":99627,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/posts\/99625\/revisions\/99627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/media\/99626"}],"wp:attachment":[{"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/media?parent=99625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/categories?post=99625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodamanhapelotas.com.br\/site\/wp-json\/wp\/v2\/tags?post=99625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}